{"id":113,"count":11,"description":"","link":"https:\/\/clinicagirona.cat\/en\/especialitat\/tocoginecologia\/","name":"Gynaecology","slug":"obstetrics-and-gynecology","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tocoginecologia - Especialitats - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"Equip de metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/en\/specialty\/obstetrics-and-gynecology\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tocoginecologia - Especialitats - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"Equip de metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/en\/specialty\/obstetrics-and-gynecology\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/clinica-girona-frontal-b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitat\\\/tocoginecologia\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitat\\\/tocoginecologia\\\/\",\"name\":\"Tocoginecologia - Especialitats - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"description\":\"Equip de metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitat\\\/tocoginecologia\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitat\\\/tocoginecologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tocoginecologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gynaecological Oncology - Specialties - Cl\u00ednica Girona","description":"A team of specialist doctors dedicated to the women's holistic health at all stages of life.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/en\/specialty\/obstetrics-and-gynecology\/","og_locale":"en_GB","og_type":"article","og_title":"Tocoginecologia - Especialitats - Cl\u00ednica Girona","og_description":"Equip de metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida.","og_url":"https:\/\/clinicagirona.cat\/en\/specialty\/obstetrics-and-gynecology\/","og_site_name":"Cl\u00ednica Girona","og_image":[{"width":900,"height":608,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/clinica-girona-frontal-b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/clinicagirona.cat\/especialitat\/tocoginecologia\/","url":"https:\/\/clinicagirona.cat\/especialitat\/tocoginecologia\/","name":"Gynaecological Oncology - Specialties - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"description":"A team of specialist doctors dedicated to the women's holistic health at all stages of life.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/especialitat\/tocoginecologia\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/especialitat\/tocoginecologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Tocoginecologia"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"We look after your health, we look after you","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/en\/wp-json\/wp\/v2\/product_cat\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/clinicagirona.cat\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/clinicagirona.cat\/en\/wp-json\/wp\/v2\/product?product_cat=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}