{"id":29125,"date":"2025-05-07T13:10:21","date_gmt":"2025-05-07T11:10:21","guid":{"rendered":"https:\/\/clinicagirona.cat\/?page_id=29125"},"modified":"2026-02-10T16:09:50","modified_gmt":"2026-02-10T15:09:50","slug":"cirugia-general","status":"publish","type":"page","link":"https:\/\/clinicagirona.cat\/es\/especialitats\/cirurgia-general\/","title":{"rendered":"Cirug\u00eda General"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29125\" class=\"elementor elementor-29125\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-87be594 e-flex e-con-boxed e-con e-parent\" data-id=\"87be594\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae42b2d wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"ae42b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Especialitat de Cirurgia General de Cl\u00ednica Girona: Solucions quir\u00fargiques avan\u00e7ades per a la seva salut<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-ce2f3f6 e-flex e-con-boxed e-con e-parent\" data-id=\"ce2f3f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-826aa5e e-con-full e-flex e-con e-child\" data-id=\"826aa5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-969a311 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"969a311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Contacte<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-005973b elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"005973b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-pin\" viewBox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Primera Planta \/ M\u00f2dul B<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mobile-alt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 0H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h224c26.5 0 48-21.5 48-48V48c0-26.5-21.5-48-48-48zM160 480c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm112-108c0 6.6-5.4 12-12 12H60c-6.6 0-12-5.4-12-12V60c0-6.6 5.4-12 12-12h200c6.6 0 12 5.4 12 12v312z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">972 224 099<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dabf0aa e-con-full e-flex e-con e-child\" data-id=\"dabf0aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21119cb color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"21119cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A l&#8217;especialitat de Cirurgia General de Cl\u00ednica Girona disposem d&#8217;un equip altament qualificat i amb una \u00e0mplia experi\u00e8ncia en el tractament quir\u00fargic d&#8217;una extensa varietat de malalties i condicions. La nostra prioritat \u00e9s oferir-li una atenci\u00f3 integral, des del diagn\u00f2stic fins a la recuperaci\u00f3 postoperat\u00f2ria, amb les t\u00e8cniques m\u00e9s innovadores i un <b>enfocament centrat en el seu benestar.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a282ab2 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"a282ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entenem que la perspectiva d&#8217;una intervenci\u00f3 quir\u00fargica pot generar preocupaci\u00f3. El nostre equip li proporcionar\u00e0 tota la informaci\u00f3 necess\u00e0ria sobre el procediment, respondr\u00e0 a les seves preguntes i guiar\u00e0 cada etapa del seu proc\u00e9s amb l&#8217;objectiu d&#8217;aconseguir una <strong>recuperaci\u00f3 r\u00e0pida i efica\u00e7<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1281311 e-flex e-con-boxed e-con e-parent\" data-id=\"1281311\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3cffa wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"2d3cffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element with-title\">\n\n\t\t\t\t\t\t\t<h3 class=\"wd-el-title title element-title\">Professionals:<\/h3>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;element_title&quot;:&quot;Professionals:&quot;,&quot;element_title_tag&quot;:&quot;h3&quot;,&quot;include&quot;:null,&quot;taxonomies&quot;:[&quot;85&quot;],&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;hide_out_of_stock&quot;:&quot;yes&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:20,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34251 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"1\" data-id=\"34251\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-clara-codony-bassols\/\" class=\"product-image-link\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-clara-codony-bassols\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34251\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-clara-codony-bassols\/\">Dra. Clara Codony Bassols<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34486 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"2\" data-id=\"34486\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-natalia-cornella-i-garceso\/\" class=\"product-image-link\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-natalia-cornella-i-garceso\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34486\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-natalia-cornella-i-garceso\/\">Dra. Nat\u00e0lia Cornell\u00e0 i Garceso<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34084 status-publish last instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"3\" data-id=\"34084\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ramon-farres-coll\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ramon-farres-coll\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34084\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ramon-farres-coll\/\">Dr. Ramon Farr\u00e9s Coll<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34496 status-publish first instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"4\" data-id=\"34496\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jose-ricardo-frago-montanuy\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Jos\u00e9 Ricardo Frago Montanuy\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jose-ricardo-frago-montanuy\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Jos\u00e9 Ricardo Frago Montanuy\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jose-Ricardo-Frago-Montanuy-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jose-ricardo-frago-montanuy\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34496\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jose-ricardo-frago-montanuy\/\">Dr. Jos\u00e9 Ricardo Frago Montanuy<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-33681 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"5\" data-id=\"33681\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jordi-girones-vila\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Jordi Giron\u00e8s Vil\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-1.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jordi-girones-vila\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Jordi Giron\u00e8s Vil\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Jordi-Girones-Vila-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jordi-girones-vila\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33681\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jordi-girones-vila\/\">Dr. Jordi Giron\u00e8s Vil\u00e0<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-33652 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"6\" data-id=\"33652\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-ferran-gomez-castella\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Joan Ferran G\u00f3mez Castell\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-ferran-gomez-castella\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Joan Ferran G\u00f3mez Castell\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Ferran-Gomez-Castella-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-ferran-gomez-castella\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33652\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-ferran-gomez-castella\/\">Dr. Joan Ferran G\u00f3mez Castell\u00e0<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-33782 status-publish last instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"7\" data-id=\"33782\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-encarnacion-piedrafita-serra\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Encarnaci\u00f3n Piedrafita Serra\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-encarnacion-piedrafita-serra\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Encarnaci\u00f3n Piedrafita Serra\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Encarnacion-Piedrafita-Serra-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-encarnacion-piedrafita-serra\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33782\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-encarnacion-piedrafita-serra\/\">Dra. Encarna Piedrafita i Serra<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34021 status-publish first instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"8\" data-id=\"34021\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-xavier-planellas-gelis\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Xavier Planellas Gelis\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-xavier-planellas-gelis\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Xavier Planellas Gelis\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Xavier-Planellas-Gelis-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-xavier-planellas-gelis\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34021\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-xavier-planellas-gelis\/\">Dr. Xavier Planellas Gelis<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34026 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"9\" data-id=\"34026\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-pere-planellas-gine\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Pere Planellas Gin\u00e9\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-pere-planellas-gine\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Pere Planellas Gin\u00e9\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Pere-Planellas-Gine-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-pere-planellas-gine\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34026\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-pere-planellas-gine\/\">Dr. Pere Planellas Gin\u00e9<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34042 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"10\" data-id=\"34042\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-manuel-puig-costa\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Manuel Puig Costa\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-manuel-puig-costa\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Manuel Puig Costa\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Manuel-Puig-Costa-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-manuel-puig-costa\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34042\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-manuel-puig-costa\/\">Dr. Manuel Puig Costa<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34127 status-publish last instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"11\" data-id=\"34127\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marcel-pujadas-de-palol\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marcel-pujadas-de-palol\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34127\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marcel-pujadas-de-palol\/\">Dr. Marcel Pujadas de Palol<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34094 status-publish first instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"12\" data-id=\"34094\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jaume-torramade-ribas\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Jaume Torramad\u00e9 Ribas\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jaume-torramade-ribas\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Jaume Torramad\u00e9 Ribas\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Jaume-Torramade-Ribas-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jaume-torramade-ribas\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34094\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-jaume-torramade-ribas\/\">Dr. Jaume Torramad\u00e9 Ribas<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-alt wd-col product-grid-item product type-product post-34098 status-publish instock product_cat-cirurgia-general has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"13\" data-id=\"34098\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-francesc-tuca-rodriguez\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Francesc Tuca Rodr\u00edguez\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-francesc-tuca-rodriguez\/\" aria-label=\"Imagen de producto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Francesc Tuca Rodr\u00edguez\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Francesc-Tuca-Rodriguez-fitxa.jpg 900w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-francesc-tuca-rodriguez\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34098\"\n\t\t\t\t>Vista r\u00e0pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-francesc-tuca-rodriguez\/\">Dr. Francesc Tuca Rodr\u00edguez<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/cirurgia-general\/\" rel=\"tag\">Cirurgia General<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div><\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Especialitat de Cirurgia General de Cl\u00ednica Girona: Solucions quir\u00fargiques avan\u00e7ades per a la seva salut Contacte Primera Planta \/ M\u00f2dul<\/p>","protected":false},"author":1,"featured_media":32187,"parent":28790,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29125","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cirurgia General - Cl\u00ednica Girona - Especialitats<\/title>\n<meta name=\"description\" content=\"Al Servei de Cirurgia General de Cl\u00ednica Girona, comptem amb un equip de cirurgians altament qualificats i amb una \u00e0mplia experi\u00e8ncia en el tractament quir\u00fargic d&#039;una extensa varietat de malalties i condicions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/especialidades\/cirugia-general\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cirurgia General - Cl\u00ednica Girona - Especialitats\" \/>\n<meta property=\"og:description\" content=\"Al Servei de Cirurgia General de Cl\u00ednica Girona, comptem amb un equip de cirurgians altament qualificats i amb una \u00e0mplia experi\u00e8ncia en el tractament quir\u00fargic d&#039;una extensa varietat de malalties i condicions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/especialidades\/cirugia-general\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T15:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cirurgia-general-banner-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/\",\"name\":\"Cirurgia General - Cl\u00ednica Girona - Especialitats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cirurgia-general-banner-.jpg\",\"datePublished\":\"2025-05-07T11:10:21+00:00\",\"dateModified\":\"2026-02-10T15:09:50+00:00\",\"description\":\"Al Servei de Cirurgia General de Cl\u00ednica Girona, comptem amb un equip de cirurgians altament qualificats i amb una \u00e0mplia experi\u00e8ncia en el tractament quir\u00fargic d'una extensa varietat de malalties i condicions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cirurgia-general-banner-.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cirurgia-general-banner-.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/cirurgia-general\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialitats\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cirurgia General\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cirug\u00eda General - Cl\u00ednica Girona - Especialidades","description":"En el Servicio de Cirug\u00eda General de Cl\u00ednica Girona, contamos con un equipo de cirujanos altamente cualificados y con una amplia experiencia en el tratamiento quir\u00fargico de una extensa variedad de enfermedades y condiciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/especialidades\/cirugia-general\/","og_locale":"es_ES","og_type":"article","og_title":"Cirurgia General - Cl\u00ednica Girona - Especialitats","og_description":"Al Servei de Cirurgia General de Cl\u00ednica Girona, comptem amb un equip de cirurgians altament qualificats i amb una \u00e0mplia experi\u00e8ncia en el tractament quir\u00fargic d'una extensa varietat de malalties i condicions.","og_url":"https:\/\/clinicagirona.cat\/es\/especialidades\/cirugia-general\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_modified_time":"2026-02-10T15:09:50+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cirurgia-general-banner-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/","url":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/","name":"Cirug\u00eda General - Cl\u00ednica Girona - Especialidades","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cirurgia-general-banner-.jpg","datePublished":"2025-05-07T11:10:21+00:00","dateModified":"2026-02-10T15:09:50+00:00","description":"En el Servicio de Cirug\u00eda General de Cl\u00ednica Girona, contamos con un equipo de cirujanos altamente cualificados y con una amplia experiencia en el tratamiento quir\u00fargico de una extensa variedad de enfermedades y condiciones.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cirurgia-general-banner-.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cirurgia-general-banner-.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/especialitats\/cirurgia-general\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Especialitats","item":"https:\/\/clinicagirona.cat\/especialitats\/"},{"@type":"ListItem","position":3,"name":"Cirurgia General"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=29125"}],"version-history":[{"count":43,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29125\/revisions"}],"predecessor-version":[{"id":36824,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29125\/revisions\/36824"}],"up":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/28790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/32187"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=29125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}