{"id":29241,"date":"2025-05-07T14:59:08","date_gmt":"2025-05-07T12:59:08","guid":{"rendered":"https:\/\/clinicagirona.cat\/?page_id=29241"},"modified":"2026-03-11T10:53:44","modified_gmt":"2026-03-11T09:53:44","slug":"digestologia","status":"publish","type":"page","link":"https:\/\/clinicagirona.cat\/es\/especialitats\/digestologia\/","title":{"rendered":"Digestolog\u00eda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29241\" class=\"elementor elementor-29241\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-87be594 e-flex e-con-boxed e-con e-parent\" data-id=\"87be594\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae42b2d wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"ae42b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Digestologia a Cl\u00ednica Girona: Cuidem la seva salut digestiva<br \/>\n<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-a97af87 e-flex e-con-boxed e-con e-parent\" data-id=\"a97af87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7458718 e-con-full e-flex e-con e-child\" data-id=\"7458718\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4762d13 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"4762d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Contacte<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d346d elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"59d346d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-pin\" viewBox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Primera planta \/ M\u00f2dul B<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mobile-alt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 0H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h224c26.5 0 48-21.5 48-48V48c0-26.5-21.5-48-48-48zM160 480c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm112-108c0 6.6-5.4 12-12 12H60c-6.6 0-12-5.4-12-12V60c0-6.6 5.4-12 12-12h200c6.6 0 12 5.4 12 12v312z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">972 010 349<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0efb68b e-con-full e-flex e-con e-child\" data-id=\"0efb68b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-138be0b color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"138be0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A l&#8217;especialitat de Digestologia de Cl\u00ednica Girona disposem d&#8217;un equip dedicat al diagn\u00f2stic i tractament de les malalties de l&#8217;aparell digestiu: es\u00f2fag, est\u00f3mac, intest\u00ed prim, c\u00f2lon, recte, fetge, vies biliars i p\u00e0ncrees. Entenem la import\u00e0ncia d&#8217;una bona salut digestiva per al seu benestar general i ens comprometem a oferir-li una atenci\u00f3 integral, personalitzada i amb les <b>t\u00e8cniques m\u00e9s avan\u00e7ades<\/b>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd85cf color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"2fd85cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sabem que els problemes digestius poden ser molt molestos i afectar la seva qualitat de vida. El nostre equip li oferir\u00e0 una avaluaci\u00f3 exhaustiva, un <strong>diagn\u00f2stic prec\u00eds<\/strong> i un pla de tractament adaptat a les seves necessitats espec\u00edfiques amb l&#8217;objectiu d&#8217;alleujar els seus s\u00edmptomes i millorar la seva salut digestiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-2052c67 e-flex e-con-boxed e-con e-parent\" data-id=\"2052c67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4be343 elementor-widget elementor-widget-n-accordion\" data-id=\"f4be343\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2560\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2560\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Servei ambulatori <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2560\" class=\"elementor-element elementor-element-72885b4 e-con-full e-flex e-con e-child\" data-id=\"72885b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e17a0d5 elementor-widget elementor-widget-wd_text_block\" data-id=\"e17a0d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left color-primary\">\n\t\t\t\n\t\t\t<ul><li>Endosc\u00f2pia digestiva diagn\u00f2stica i terap\u00e8utica.<\/li><li>CREP.<\/li><li>Bal\u00f3 intrag\u00e0stric.<\/li><li>C\u00e0psula Endosc\u00f2pica Diagn\u00f2stica.<\/li><li>Esclerosi.<\/li><li>Gastrostomia percut\u00e0nia endosc\u00f2pica.<\/li><li>Bi\u00f2psia hep\u00e0tica.<\/li><li>Bi\u00f2psia intestinal.<\/li><li>Dilatacions de pilor, esof\u00e0g, anal\u2026<\/li><li>Mucosectomies.<\/li><li>Polipectomia.<\/li><\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-cd15176 e-flex e-con-boxed e-con e-parent\" data-id=\"cd15176\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b326483 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"b326483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element with-title\">\n\n\t\t\t\t\t\t\t<h3 class=\"wd-el-title title element-title\">Professionals:<\/h3>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g wd-loop-builder-off\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;sync_group_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;element_title&quot;:&quot;Professionals:&quot;,&quot;element_title_tag&quot;:&quot;h3&quot;,&quot;include&quot;:null,&quot;taxonomies&quot;:[&quot;91&quot;],&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;hide_out_of_stock&quot;:&quot;yes&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;list_spacing&quot;:null,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_custom_hover&quot;:null,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34144 status-publish instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"1\" data-id=\"34144\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marco-aurelio-alburquerque-miranda\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. Marco Aurelio Alburquerque Miranda\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Marco Aurelio Alburquerque Miranda\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Marco Aurelio Alburquerque Miranda\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Marco-Aurelio-Alburquerque-Miranda-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marco-aurelio-alburquerque-miranda\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34144\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-marco-aurelio-alburquerque-miranda\/\">Dr. Marco Aurelio Alburquerque Miranda<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-36394 status-publish instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"2\" data-id=\"36394\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-montserrat-figa-francesch\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Montserrat Figa Francesch\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Montserrat Figa Francesch\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Montserrat Figa Francesch fitxa\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/02\/Dra-Montserrat-Figa-Francesch-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-montserrat-figa-francesch\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"36394\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-montserrat-figa-francesch\/\">Dra. Montserrat Figa Francesch<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-33965 status-publish last instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"3\" data-id=\"33965\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ferran-gonzalez-huix-llado\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. Ferran Gonz\u00e1lez-Huix Llado\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ferran-gonzalez-huix-llado\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33965\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-ferran-gonzalez-huix-llado\/\">Dr. Ferran Gonz\u00e1lez-Huix Llado<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34641 status-publish first instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"4\" data-id=\"34641\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-laura-gutierrez\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Laura Guti\u00e9rrez R\u00edos\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-laura-gutierrez\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34641\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-laura-gutierrez\/\">Dra. Laura Guti\u00e9rrez R\u00edos<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34269 status-publish instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"5\" data-id=\"34269\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-pijoan-comas\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Eva Pijoan Comas\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-pijoan-comas\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34269\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-pijoan-comas\/\">Dra. Eva Pijoan Comas<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-33805 status-publish instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"6\" data-id=\"33805\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-puig-gonzalez\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Maria Puig Gonz\u00e1lez\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-puig-gonzalez\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33805\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-puig-gonzalez\/\">Dra. Maria Puig Gonz\u00e1lez<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34163 status-publish last instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"7\" data-id=\"34163\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-alba-luz-vargas-garcia\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Alba Luz Vargas Garc\u00eda\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-alba-luz-vargas-garcia\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34163\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-alba-luz-vargas-garcia\/\">Dra. Alba Luz Vargas Garc\u00eda<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34490 status-publish first instock product_cat-digestologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"8\" data-id=\"34490\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-vayreda-domingo\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Eva Vayreda Domingo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctora-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-vayreda-domingo\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34490\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-eva-vayreda-domingo\/\">Dra. Eva Vayreda Domingo<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/digestologia\/\" rel=\"tag\">Digestologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Digestolog\u00eda en Cl\u00ednica Girona: Cuidamos su salud digestiva Contacto Primera planta \/ M\u00f3dulo B 972 010 349 A la especialidad<\/p>","protected":false},"author":1,"featured_media":31977,"parent":28790,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29241","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digestologia - Cl\u00ednica Girona - Especialitats<\/title>\n<meta name=\"description\" content=\"A l&#039;especialitat de Digestologia de Cl\u00ednica Girona, disposem d&#039;un equip de metges especialistes dedicats al diagn\u00f2stic i tractament de les malalties de l&#039;aparell digestiu: es\u00f2fag, est\u00f3mac, intest\u00ed prim, c\u00f2lon, recte, fetge, vies biliars i p\u00e0ncrees.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/especialidades\/digestologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digestologia - Cl\u00ednica Girona - Especialitats\" \/>\n<meta property=\"og:description\" content=\"A l&#039;especialitat de Digestologia de Cl\u00ednica Girona, disposem d&#039;un equip de metges especialistes dedicats al diagn\u00f2stic i tractament de les malalties de l&#039;aparell digestiu: es\u00f2fag, est\u00f3mac, intest\u00ed prim, c\u00f2lon, recte, fetge, vies biliars i p\u00e0ncrees.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/especialidades\/digestologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T09:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Digestologia-banner-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/\",\"name\":\"Digestologia - Cl\u00ednica Girona - Especialitats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Digestologia-banner-.jpg\",\"datePublished\":\"2025-05-07T12:59:08+00:00\",\"dateModified\":\"2026-03-11T09:53:44+00:00\",\"description\":\"A l'especialitat de Digestologia de Cl\u00ednica Girona, disposem d'un equip de metges especialistes dedicats al diagn\u00f2stic i tractament de les malalties de l'aparell digestiu: es\u00f2fag, est\u00f3mac, intest\u00ed prim, c\u00f2lon, recte, fetge, vies biliars i p\u00e0ncrees.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Digestologia-banner-.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Digestologia-banner-.jpg\",\"width\":900,\"height\":600,\"caption\":\"Metge digest\u00f2leg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/digestologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialitats\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Digestologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digestolog\u00eda - Cl\u00ednica Girona - Especialidades","description":"En la especialidad de Digestolog\u00eda de Cl\u00ednica Girona, contamos con un equipo de m\u00e9dicos especialistas dedicados al diagn\u00f3stico y tratamiento de las enfermedades del aparato digestivo: es\u00f3fago, est\u00f3mago, intestino delgado, colon, recto, h\u00edgado, v\u00edas biliares y p\u00e1ncreas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/especialidades\/digestologia\/","og_locale":"es_ES","og_type":"article","og_title":"Digestologia - Cl\u00ednica Girona - Especialitats","og_description":"A l'especialitat de Digestologia de Cl\u00ednica Girona, disposem d'un equip de metges especialistes dedicats al diagn\u00f2stic i tractament de les malalties de l'aparell digestiu: es\u00f2fag, est\u00f3mac, intest\u00ed prim, c\u00f2lon, recte, fetge, vies biliars i p\u00e0ncrees.","og_url":"https:\/\/clinicagirona.cat\/es\/especialidades\/digestologia\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_modified_time":"2026-03-11T09:53:44+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Digestologia-banner-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/","url":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/","name":"Digestolog\u00eda - Cl\u00ednica Girona - Especialidades","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Digestologia-banner-.jpg","datePublished":"2025-05-07T12:59:08+00:00","dateModified":"2026-03-11T09:53:44+00:00","description":"En la especialidad de Digestolog\u00eda de Cl\u00ednica Girona, contamos con un equipo de m\u00e9dicos especialistas dedicados al diagn\u00f3stico y tratamiento de las enfermedades del aparato digestivo: es\u00f3fago, est\u00f3mago, intestino delgado, colon, recto, h\u00edgado, v\u00edas biliares y p\u00e1ncreas.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/especialitats\/digestologia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Digestologia-banner-.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Digestologia-banner-.jpg","width":900,"height":600,"caption":"Metge digest\u00f2leg"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/especialitats\/digestologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Especialitats","item":"https:\/\/clinicagirona.cat\/especialitats\/"},{"@type":"ListItem","position":3,"name":"Digestologia"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=29241"}],"version-history":[{"count":40,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29241\/revisions"}],"predecessor-version":[{"id":38708,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29241\/revisions\/38708"}],"up":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/28790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/31977"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=29241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}