{"id":29632,"date":"2025-05-08T16:22:39","date_gmt":"2025-05-08T14:22:39","guid":{"rendered":"https:\/\/clinicagirona.cat\/?page_id=29632"},"modified":"2026-03-11T11:28:49","modified_gmt":"2026-03-11T10:28:49","slug":"tocoginecologia","status":"publish","type":"page","link":"https:\/\/clinicagirona.cat\/es\/especialitats\/tocoginecologia\/","title":{"rendered":"Tocoginecolog\u00eda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29632\" class=\"elementor elementor-29632\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-87be594 e-flex e-con-boxed e-con e-parent\" data-id=\"87be594\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae42b2d wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"ae42b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Especialitat de Tocoginecologia a Cl\u00ednica Girona: Cuidem la salut integral de la dona<br \/>\n<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-2fe71ff e-flex e-con-boxed e-con e-parent\" data-id=\"2fe71ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c02dcb9 e-con-full e-flex e-con e-child\" data-id=\"c02dcb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31f8efb wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"31f8efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Contacte<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-582b4f5 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"582b4f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-pin\" viewBox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Primera Planta \/ M\u00f2dul A<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mobile-alt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 0H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h224c26.5 0 48-21.5 48-48V48c0-26.5-21.5-48-48-48zM160 480c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm112-108c0 6.6-5.4 12-12 12H60c-6.6 0-12-5.4-12-12V60c0-6.6 5.4-12 12-12h200c6.6 0 12 5.4 12 12v312z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">972 483 838<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">De 08:00 h a 21:00 hores.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53efa67 e-con-full e-flex e-con e-child\" data-id=\"53efa67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dee5cda color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"dee5cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A l&#8217;especialitat de Tocoginecologia de Cl\u00ednica Girona disposem d&#8217;un equip dedicat a la salut integral de la dona en totes les etapes de la seva vida: adolesc\u00e8ncia, edat f\u00e8rtil, embar\u00e0s, part, postpart i menopausa. La nostra prioritat \u00e9s oferir una atenci\u00f3 personalitzada, propera i amb les <strong>t\u00e8cniques m\u00e9s avan\u00e7ades<\/strong> per garantir el seu benestar f\u00edsic i emocional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fced5ce color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"fced5ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entenem la import\u00e0ncia d&#8217;una atenci\u00f3 ginecol\u00f2gica i obst\u00e8trica de qualitat per a la seva salut i benestar. El nostre equip li oferir\u00e0 una avaluaci\u00f3 exhaustiva, un diagn\u00f2stic prec\u00eds i un pla de tractament adaptat a les seves necessitats espec\u00edfiques, amb l&#8217;objectiu de promoure la seva salut i acompanyar-la en moments tan importants com<strong> l&#8217;embar\u00e0s i el part<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-a4ffc3f e-flex e-con-boxed e-con e-parent\" data-id=\"a4ffc3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0b9de1 elementor-widget elementor-widget-n-accordion\" data-id=\"c0b9de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2020\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2020\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Especialitat Quir\u00fargica <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2020\" class=\"elementor-element elementor-element-ce1c355 e-con-full e-flex e-con e-child\" data-id=\"ce1c355\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99eb7f2 elementor-widget elementor-widget-wd_text_block\" data-id=\"99eb7f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left color-primary\">\n\t\t\t\n\t\t\t<ul><li>Part \/ Ces\u00e0ria.<\/li><li>Ces\u00e0ries \u201camables\u201d o \u201cpro-vincle\u201d.<\/li><li>Legrat.<\/li><li>Histerectomia.<\/li><li>Laparosc\u00f2pia diagn\u00f2stica i terap\u00e8utica.<\/li><li>Bi\u00f2psies.<\/li><li>Cirurgia de la mama.<\/li><li>Cirurgia ginecol\u00f2gica i laparosc\u00f2pica.<\/li><li>Cirurgia oncol\u00f2gica ginecol\u00f2gica.<\/li><li>Extracci\u00f3 o\u00f2cits.<\/li><\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-ff1c252 e-flex e-con-boxed e-con e-parent\" data-id=\"ff1c252\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45462da wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"45462da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element with-title\">\n\n\t\t\t\t\t\t\t<h3 class=\"wd-el-title title element-title\">Professionals:<\/h3>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g wd-loop-builder-off\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;sync_group_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;element_title&quot;:&quot;Professionals:&quot;,&quot;element_title_tag&quot;:&quot;h3&quot;,&quot;include&quot;:null,&quot;taxonomies&quot;:[&quot;113&quot;],&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;hide_out_of_stock&quot;:&quot;yes&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:20,&quot;list_spacing&quot;:null,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_custom_hover&quot;:null,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34294 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"1\" data-id=\"34294\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ariadna-danes-barris\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Ariadna Dan\u00e9s Barris\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Ariadna Dan\u00e9s Barris\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Ariadna Dan\u00e9s Barris\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ariadna-Danes-Barris-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ariadna-danes-barris\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34294\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ariadna-danes-barris\/\">Dra. Ariadna Dan\u00e9s Barris<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34264 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"2\" data-id=\"34264\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-font-roig\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Maria Font Roig\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Maria Font Roig\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Maria Font Roig\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Maria-Font-Roig-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-font-roig\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34264\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-font-roig\/\">Dra. Maria Font Roig<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34228 status-publish last instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"3\" data-id=\"34228\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-olga-guell-rojo\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Olga G\u00fcell Rojo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Olga G\u00fcell Rojo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Olga G\u00fcell Rojo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Olga-Guell-Rojo-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-olga-guell-rojo\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34228\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-olga-guell-rojo\/\">Dra. Olga G\u00fcell Rojo<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34475 status-publish first instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"4\" data-id=\"34475\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-nuria-haro-jorda\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. N\u00faria Haro Jord\u00e0\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. N\u00faria Haro Jord\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora N\u00faria Haro Jord\u00e0\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Nuria-Haro-Jorda-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-nuria-haro-jorda\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34475\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-nuria-haro-jorda\/\">Dra. N\u00faria Haro Jord\u00e0<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34396 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"5\" data-id=\"34396\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-roser-maso-vallmajo\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Roser Mas\u00f3 Vallmaj\u00f3\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Roser Mas\u00f3 Vallmaj\u00f3\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Roser Mas\u00f3 Vallmaj\u00f3\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Roser-Maso-Vallmajo-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-roser-maso-vallmajo\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34396\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-roser-maso-vallmajo\/\">Dra. Roser Mas\u00f3 Vallmaj\u00f3<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34813 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"6\" data-id=\"34813\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-munoz\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. Joan Mel\u00e9ndez Mu\u00f1oz\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/doctor-sense-foto.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-munoz\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34813\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-munoz\/\">Dr. Joan Mel\u00e9ndez Mu\u00f1oz<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-33669 status-publish last instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"7\" data-id=\"33669\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-rusinol\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. Joan Mel\u00e9ndez Rusi\u00f1ol\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Joan Mel\u00e9ndez Rusi\u00f1ol\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Joan Mel\u00e9ndez Rusi\u00f1ol\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dr.-Joan-Melendez-Rusinol-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-rusinol\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33669\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-joan-melendez-rusinol\/\">Dr. Joan Mel\u00e9ndez Rusi\u00f1ol<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-33995 status-publish first instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"8\" data-id=\"33995\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-miguel-montalvo-ibarra\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. Miguel Montalvo Ibarra\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. Miguel Montalvo Ibarra\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor Miguel Montalvo Ibarra\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Miguel-Montalvo-Ibarra-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-miguel-montalvo-ibarra\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33995\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-miguel-montalvo-ibarra\/\">Dr. Miguel Montalvo Ibarra<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34050 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"9\" data-id=\"34050\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-alex-querol-badenas\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dr. \u00c0lex Querol Badenas\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dr. \u00c0lex Querol Badenas\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctor \u00c0lex Querol Badenas\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dr.-Alex-Querol-Badenas-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-alex-querol-badenas\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34050\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dr-alex-querol-badenas\/\">Dr. \u00c0lex Querol Badenas<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-34262 status-publish instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"10\" data-id=\"34262\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ma-angels-ribary-domingo\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Maria \u00c0ngels Ribary Domingo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. M\u00aa Angels Ribary Domingo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora M\u00aa Angels Ribary Domingo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/07\/Dra.-Ma-Angels-Ribary-Domingo-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ma-angels-ribary-domingo\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"34262\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-ma-angels-ribary-domingo\/\">Dra. Maria \u00c0ngels Ribary Domingo<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-col wd-hover-alt product-grid-item product type-product post-33811 status-publish last instock product_cat-tocoginecologia has-post-thumbnail shipping-taxable product-type-simple\" data-loop=\"11\" data-id=\"33811\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-rosa-vila-hernandez\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Dra. Maria Rosa Vila Hern\u00e1ndez\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Dra. Maria Rosa Vila Hern\u00e1ndez\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"wd-product-img-hover hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-533x800.jpg\" class=\"attachment-large size-large\" alt=\"Doctora Maria Rosa Vila Hern\u00e1ndez\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-533x800.jpg 533w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-200x300.jpg 200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-768x1152.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-430x645.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-700x1050.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa-150x225.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Dra.-Maria-Rosa-Vila-Hernandez-fitxa.jpg 900w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-rosa-vila-hernandez\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"33811\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tVista r\u00e0pida\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/clinicagirona.cat\/es\/professionals-medics\/dra-maria-rosa-vila-hernandez\/\">Dra. Maria Rosa Vila Hern\u00e1ndez<\/a><\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/especialitat\/tocoginecologia\/\" rel=\"tag\">Tocoginecologia<\/a>\t\t<\/div>\n\t\t\t\t<div class=\"wrap-price\">\n\t\t\t<div class=\"swap-wrapp\">\n\t\t\t\t<div class=\"swap-elements\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-add-btn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Especialidad de Tocoginecolog\u00eda en Cl\u00ednica Girona: Cuidamos la salud integral de la mujer Contacto Primera Planta \/ M\u00f3dulo A 972<\/p>","protected":false},"author":1,"featured_media":32170,"parent":28790,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29632","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tocoginecologia - Cl\u00ednica Girona - Especialitats<\/title>\n<meta name=\"description\" content=\"Metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida: adolesc\u00e8ncia, edat f\u00e8rtil, embar\u00e0s, part, postpart i menopausa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/especialidades\/tocoginecologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tocoginecologia - Cl\u00ednica Girona - Especialitats\" \/>\n<meta property=\"og:description\" content=\"Metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida: adolesc\u00e8ncia, edat f\u00e8rtil, embar\u00e0s, part, postpart i menopausa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/especialidades\/tocoginecologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T10:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Tocoginecologia-banner-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/\",\"name\":\"Tocoginecologia - Cl\u00ednica Girona - Especialitats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Tocoginecologia-banner-.jpg\",\"datePublished\":\"2025-05-08T14:22:39+00:00\",\"dateModified\":\"2026-03-11T10:28:49+00:00\",\"description\":\"Metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida: adolesc\u00e8ncia, edat f\u00e8rtil, embar\u00e0s, part, postpart i menopausa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Tocoginecologia-banner-.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Tocoginecologia-banner-.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/tocoginecologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialitats\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/especialitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tocoginecologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tocoginecolog\u00eda - Cl\u00ednica Girona - Especialidades","description":"M\u00e9dicos especialistas dedicados a la salud integral de la mujer en todas las etapas de su vida: adolescencia, edad f\u00e9rtil, embarazo, parto, posparto y menopausia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/especialidades\/tocoginecologia\/","og_locale":"es_ES","og_type":"article","og_title":"Tocoginecologia - Cl\u00ednica Girona - Especialitats","og_description":"Metges especialistes dedicats a la salut integral de la dona en totes les etapes de la seva vida: adolesc\u00e8ncia, edat f\u00e8rtil, embar\u00e0s, part, postpart i menopausa.","og_url":"https:\/\/clinicagirona.cat\/es\/especialidades\/tocoginecologia\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_modified_time":"2026-03-11T10:28:49+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Tocoginecologia-banner-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/","url":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/","name":"Tocoginecolog\u00eda - Cl\u00ednica Girona - Especialidades","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Tocoginecologia-banner-.jpg","datePublished":"2025-05-08T14:22:39+00:00","dateModified":"2026-03-11T10:28:49+00:00","description":"M\u00e9dicos especialistas dedicados a la salud integral de la mujer en todas las etapas de su vida: adolescencia, edad f\u00e9rtil, embarazo, parto, posparto y menopausia.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Tocoginecologia-banner-.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Tocoginecologia-banner-.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/especialitats\/tocoginecologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Especialitats","item":"https:\/\/clinicagirona.cat\/especialitats\/"},{"@type":"ListItem","position":3,"name":"Tocoginecologia"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=29632"}],"version-history":[{"count":43,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29632\/revisions"}],"predecessor-version":[{"id":38762,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/29632\/revisions\/38762"}],"up":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/28790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/32170"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=29632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}