{"id":31078,"date":"2025-05-19T10:43:04","date_gmt":"2025-05-19T08:43:04","guid":{"rendered":"https:\/\/clinicagirona.cat\/?page_id=31078"},"modified":"2026-03-10T12:55:22","modified_gmt":"2026-03-10T11:55:22","slug":"grupo-clinica-girona","status":"publish","type":"page","link":"https:\/\/clinicagirona.cat\/es\/grup-clinica-girona\/","title":{"rendered":"Grup Cl\u00ednica Girona"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"31078\" class=\"elementor elementor-31078\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-e15afb9 e-flex e-con-boxed e-con e-parent\" data-id=\"e15afb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cfbd4d3 e-con-full e-flex e-con e-child\" data-id=\"cfbd4d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ec5a57 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"5ec5a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xxl\">Grup Cl\u00ednica Girona:<br \/>\n<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p>Cl\u00ednica Girona es una cl\u00ednica quir\u00fargica y m\u00e9dica <strong>fundada en 1934<\/strong>. Con los a\u00f1os se ha convertido en el eje de un grupo de empresas que, atendiendo a la filosof\u00eda fundacional, es propiedad mayoritariamente de los profesionales que ejercen su actividad en el centro o en las unidades espec\u00edficas integradas.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-bc4484a e-grid wd-section-stretch e-con-boxed e-con e-parent\" data-id=\"bc4484a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-cab3ff7 e-flex e-con-boxed e-con e-child\" data-id=\"cab3ff7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f09cbb elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"7f09cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.anatomiapatologica.cat\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Logotipo azul de Anatom\u00eda Patol\u00f3gica Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-color-400.png\" class=\"attachment-full size-full\" alt=\"Anatom\u00eda Patol\u00f3gica Cl\u00ednica Girona logo color\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-color-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-color-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-color-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/anatomia-patologica-logo-color-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.anatomiapatologica.cat\/\" target=\"_blank\">\n\t\t\tAnatom\u00eda Patol\u00f3gica\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 414 040\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e692f91 e-con-full e-flex e-con e-child\" data-id=\"e692f91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffab8d5 elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"ffab8d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.cagi.cat\/ca\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-blau-400-.png\" class=\"attachment-full size-full\" alt=\"Logotipo azul del Centre d&#039;An\u00e0lisis Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-blau-400-.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-blau-400--400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-blau-400--430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-blau-400--150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-400-.png\" class=\"attachment-full size-full\" alt=\"Logotipo del Centre d&#039;An\u00e0lisis Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-400-.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-400--400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-400--430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/centre-analisis-girona-logo-400--150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.cagi.cat\/ca\" target=\"_blank\">\n\t\t\tCentre d'An\u00e0lisis Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 200 460\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20186d5 e-con-full e-flex e-con e-child\" data-id=\"20186d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eba1faf elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"eba1faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.cetir.com\/red-de-centros\/cetir-clinica-girona\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-color-400.png\" class=\"attachment-full size-full\" alt=\"Cetir logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-color-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-color-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-color-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-color-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-400.png\" class=\"attachment-full size-full\" alt=\"Cetir logotipo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/cetir-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.cetir.com\/red-de-centros\/cetir-clinica-girona\/\" target=\"_blank\">\n\t\t\tCETIR \u2013 Cl\u00ednica Girona Medicina Nuclear\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 225 599\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-162d699 e-con-full e-flex e-con e-child\" data-id=\"162d699\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f096696 elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"f096696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.diima.cat\/ca\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-color-400.png\" class=\"attachment-full size-full\" alt=\"DIIMA \u2013 Diagn\u00f2stic per la Imatge logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-color-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-color-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-color-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-color-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-400.png\" class=\"attachment-full size-full\" alt=\"DIIMA \u2013 Diagn\u00f3stico por la Imagen logo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/diima-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.diima.cat\/ca\" target=\"_blank\">\n\t\t\tDIIMA \u2013 Diagn\u00f2stic per la Imatge\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 202 684\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb4b108 e-con-full e-flex e-con e-child\" data-id=\"bb4b108\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8165dc elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"f8165dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/fisiomedicgrup.cat\/ca\/fisiomedic-girona\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Fisiom\u00e8dic Grup logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-400.png\" class=\"attachment-full size-full\" alt=\"Color del logo Fisiom\u00e8dic Grup\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/fisiomedic-grup-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/fisiomedicgrup.cat\/ca\/fisiomedic-girona\" target=\"_blank\">\n\t\t\tFisiom\u00e8dic Cl\u00ednica Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 226 255\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7adcfff e-con-full e-flex e-con e-child\" data-id=\"7adcfff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d751c3 elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"5d751c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Logo azul de Hemodin\u00e1mica Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-400.png\" class=\"attachment-full size-full\" alt=\"Logo azul de Hemodin\u00e1mica Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/hemodinamica-clinica-girona-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"#\" target=\"_blank\">\n\t\t\tHemodin\u00e0mica - Cl\u00ednica Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 204 500\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-318d5cc e-con-full e-flex e-con e-child\" data-id=\"318d5cc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b03cb7 elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"1b03cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.oftalis.com\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Institut d&#039;Oftalmologia Cl\u00ednica Girona logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-400.png\" class=\"attachment-full size-full\" alt=\"Institut d&#039;Oftalmologia Cl\u00ednica Girona logotipo\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/institut-oftalmologia-clinica-girona-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.oftalis.com\/\" target=\"_blank\">\n\t\t\tIOCG - Institut d'Oftalmologia Cl\u00ednica Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 412 413\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99a354b e-con-full e-flex e-con e-child\" data-id=\"99a354b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2cc16c elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"c2cc16c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.girofiv.com\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-blau-400-.png\" class=\"attachment-full size-full\" alt=\"Girofiv Cl\u00ednica Girona logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-blau-400-.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-blau-400--400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-blau-400--430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-blau-400--150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-400-.png\" class=\"attachment-full size-full\" alt=\"Logotipo de Girofiv Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-400-.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-400--400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-400--430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/girofiv-logo-400--150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.girofiv.com\/\" target=\"_blank\">\n\t\t\tGIROFIV Cl\u00ednica Girona - Reproducci\u00f3 Assistida\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 205 262 \t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1863ae e-con-full e-flex e-con e-child\" data-id=\"f1863ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5114cc1 elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"5114cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/www.ressonanciagirona.cat\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Resson\u00e0ncia Girona logo azul\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-400.png\" class=\"attachment-full size-full\" alt=\"Logo de Resson\u00e0ncia Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/ressonancia-clinica-girona-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/www.ressonanciagirona.cat\/\" target=\"_blank\">\n\t\t\tResson\u00e0ncia Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 410 256\t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4534212 e-con-full e-flex e-con e-child\" data-id=\"4534212\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-262429c elementor-widget elementor-widget-qi_addons_for_elementor_clients_list\" data-id=\"262429c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_clients_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-clients-list qodef-border--no qodef--hover-roll-vertical qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/unidad-del-sueno-de-girona\/\" target=\"_blank\">\n\t\t\t\t<div class=\"qodef-e-images-holder\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-main-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-blau-400.png\" class=\"attachment-full size-full\" alt=\"Logotipo azul de la Unidad del Sue\u00f1o Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-blau-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-blau-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-blau-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-blau-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hover-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"147\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-400.png\" class=\"attachment-full size-full\" alt=\"Logotipo de la Unidad del Sue\u00f1o Cl\u00ednica Girona\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-400.png 450w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-400-400x131.png 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-400-430x140.png 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/unitat-son-clinica-girona-logo-400-150x49.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t\t<a href=\"https:\/\/clinicagirona.cat\/es\/unidad-del-sueno-de-girona\/\" target=\"_blank\">\n\t\t\tUnitat del Son - Cl\u00ednica Girona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t<p class=\"qodef-e-text\">\n\t\t972 487 092 \t<\/p>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Grup Cl\u00ednica Girona: Cl\u00ednica Girona es una cl\u00ednica quir\u00fargica y m\u00e9dica fundada en 1934. Con los a\u00f1os se ha convertido en el eje<\/p>","protected":false},"author":1,"featured_media":32937,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-31078","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grup Cl\u00ednica Girona - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"La Cl\u00ednica Girona disposa d\u2019un complet quadre m\u00e8dic i la m\u00e9s moderna tecnologia per dur a terme totes les proves m\u00e8diques i quir\u00fargiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/grupo-clinica-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grup Cl\u00ednica Girona - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"La Cl\u00ednica Girona disposa d\u2019un complet quadre m\u00e8dic i la m\u00e9s moderna tecnologia per dur a terme totes les proves m\u00e8diques i quir\u00fargiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/grupo-clinica-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T11:55:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Clinica-girona-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/\",\"name\":\"Grup Cl\u00ednica Girona - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Clinica-girona-banner.jpg\",\"datePublished\":\"2025-05-19T08:43:04+00:00\",\"dateModified\":\"2026-03-10T11:55:22+00:00\",\"description\":\"La Cl\u00ednica Girona disposa d\u2019un complet quadre m\u00e8dic i la m\u00e9s moderna tecnologia per dur a terme totes les proves m\u00e8diques i quir\u00fargiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Clinica-girona-banner.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Clinica-girona-banner.jpg\",\"width\":900,\"height\":600,\"caption\":\"Edifici Cl\u00ednica Girona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/grup-clinica-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grup Cl\u00ednica Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grup Cl\u00ednica Girona - Cl\u00ednica Girona","description":"La Cl\u00ednica Girona cuenta con un completo cuadro m\u00e9dico y la m\u00e1s moderna tecnolog\u00eda para llevar a cabo todas las pruebas m\u00e9dicas y quir\u00fargicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/grupo-clinica-girona\/","og_locale":"es_ES","og_type":"article","og_title":"Grup Cl\u00ednica Girona - Cl\u00ednica Girona","og_description":"La Cl\u00ednica Girona disposa d\u2019un complet quadre m\u00e8dic i la m\u00e9s moderna tecnologia per dur a terme totes les proves m\u00e8diques i quir\u00fargiques.","og_url":"https:\/\/clinicagirona.cat\/es\/grupo-clinica-girona\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_modified_time":"2026-03-10T11:55:22+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Clinica-girona-banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/","url":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/","name":"Grup Cl\u00ednica Girona - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Clinica-girona-banner.jpg","datePublished":"2025-05-19T08:43:04+00:00","dateModified":"2026-03-10T11:55:22+00:00","description":"La Cl\u00ednica Girona cuenta con un completo cuadro m\u00e9dico y la m\u00e1s moderna tecnolog\u00eda para llevar a cabo todas las pruebas m\u00e9dicas y quir\u00fargicas.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/grup-clinica-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Clinica-girona-banner.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Clinica-girona-banner.jpg","width":900,"height":600,"caption":"Edifici Cl\u00ednica Girona"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/grup-clinica-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Grup Cl\u00ednica Girona"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/31078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=31078"}],"version-history":[{"count":205,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/31078\/revisions"}],"predecessor-version":[{"id":38627,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/pages\/31078\/revisions\/38627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/32937"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=31078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}