{"id":32810,"date":"2023-08-28T11:43:00","date_gmt":"2023-08-28T09:43:00","guid":{"rendered":"https:\/\/clinicagirona.cat\/?p=32810"},"modified":"2026-04-15T14:03:19","modified_gmt":"2026-04-15T12:03:19","slug":"clinica-girona-pone-en-funcionamiento-un-nuevo-servicio-de-ecocardiografia-fetal","status":"publish","type":"post","link":"https:\/\/clinicagirona.cat\/es\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/","title":{"rendered":"Cl\u00ednica Girona pone en funcionamiento un nuevo servicio de Ecocardiograf\u00eda Fetal"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Cl\u00ednica Girona<\/strong>&nbsp;Pone en funcionamiento un nuevo procedimiento de ecocardiograf\u00eda fetal, un m\u00e9todo preciso y seguro para la detecci\u00f3n de cardiopat\u00edas cong\u00e9nitas. Las doctoras Rosa Vila y Susana Uriel son las encargadas de realizar estas ecograf\u00edas fetales, en el M\u00f3dulo A de la Primera Planta de la&nbsp;<strong>Cl\u00ednica Girona<\/strong>&nbsp;(Tel. 972 483838).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La incidencia de cardiopat\u00edas cong\u00e9nitas se sit\u00faa entre el 0,8 y el 1 las gestantes. La mayor\u00eda (el 90% ) de las cardiopat\u00edas cong\u00e9nitas tienen lugar en gestaciones sin factores de riesgo o antecedentes conocidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La indicaci\u00f3n de realizar una ecocardiograf\u00eda fetal ha ido en aumento en los \u00faltimos a\u00f1os. Por ejemplo, la ecocardiograf\u00eda es importante en casos como: gestaciones logradas por fecundaci\u00f3n in vitro, obesidad materna, anomal\u00eda ecogr\u00e1fica extracard\u00edaca, en la toma de determinados f\u00e1rmacos durante el embarazo (antidepresivos, ansiol\u00edticos, antiepil\u00e9pticos, etc.), en pacientes diab\u00e9ticas, o con antecedentes familiares de cardiopat\u00eda, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diagn\u00f3stico prenatal que ofrece la ecocardiograf\u00eda fetal es de gran importancia, dado que permite realizar una correcta evaluaci\u00f3n de los riesgos cardiol\u00f3gicos del feto y se obtiene as\u00ed un mejor control gestacional, un mejor pron\u00f3stico y una planificaci\u00f3n del parto m\u00e1 s eficiente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1067\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-1067x800.jpg\" alt=\"Cl\u00ednica Girona pone en funcionamiento un nuevo servicio de Ecocardiograf\u00eda Fetal\" class=\"wp-image-32811\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-1067x800.jpg 1067w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-400x300.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-768x576.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-430x323.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-700x525.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal-150x113.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg 1200w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Cl\u00ednica Girona pone en marcha un nuevo procedimiento de ecocardiograf\u00eda fetal, un m\u00e9todo preciso y seguro para la detecci\u00f3n de cardiopat\u00edas cong\u00e9nitas.<\/p>","protected":false},"author":1,"featured_media":32811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-32810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"Cl\u00ednica Girona\u00a0posa en funcionament un nou procediment d\u2019ecocardiografia fetal, un m\u00e8tode prec\u00eds i segur per a la detecci\u00f3 de cardiopaties cong\u00e8nites.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/clinica-girona-pone-en-funcionamiento-un-nuevo-servicio-de-ecocardiografia-fetal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"Cl\u00ednica Girona\u00a0posa en funcionament un nou procediment d\u2019ecocardiografia fetal, un m\u00e8tode prec\u00eds i segur per a la detecci\u00f3 de cardiopaties cong\u00e8nites.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/clinica-girona-pone-en-funcionamiento-un-nuevo-servicio-de-ecocardiografia-fetal\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-28T09:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00ednica Girona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00ednica Girona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/\"},\"author\":{\"name\":\"Cl\u00ednica Girona\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\"},\"headline\":\"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal\",\"datePublished\":\"2023-08-28T09:43:00+00:00\",\"dateModified\":\"2026-04-15T12:03:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/\"},\"wordCount\":219,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ecocardiografia-Fetal.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/\",\"name\":\"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ecocardiografia-Fetal.jpg\",\"datePublished\":\"2023-08-28T09:43:00+00:00\",\"dateModified\":\"2026-04-15T12:03:19+00:00\",\"description\":\"Cl\u00ednica Girona\u00a0posa en funcionament un nou procediment d\u2019ecocardiografia fetal, un m\u00e8tode prec\u00eds i segur per a la detecci\u00f3 de cardiopaties cong\u00e8nites.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ecocardiografia-Fetal.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ecocardiografia-Fetal.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\",\"name\":\"Cl\u00ednica Girona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"caption\":\"Cl\u00ednica Girona\"},\"sameAs\":[\"https:\\\/\\\/clinicagirona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cl\u00ednica Girona pone en funcionamiento un nuevo servicio de Ecocardiograf\u00eda Fetal - Cl\u00ednica Girona","description":"Cl\u00ednica Girona pone en marcha un nuevo procedimiento de ecocardiograf\u00eda fetal, un m\u00e9todo preciso y seguro para la detecci\u00f3n de cardiopat\u00edas cong\u00e9nitas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/clinica-girona-pone-en-funcionamiento-un-nuevo-servicio-de-ecocardiografia-fetal\/","og_locale":"es_ES","og_type":"article","og_title":"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal - Cl\u00ednica Girona","og_description":"Cl\u00ednica Girona\u00a0posa en funcionament un nou procediment d\u2019ecocardiografia fetal, un m\u00e8tode prec\u00eds i segur per a la detecci\u00f3 de cardiopaties cong\u00e8nites.","og_url":"https:\/\/clinicagirona.cat\/es\/clinica-girona-pone-en-funcionamiento-un-nuevo-servicio-de-ecocardiografia-fetal\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_published_time":"2023-08-28T09:43:00+00:00","article_modified_time":"2026-04-15T12:03:19+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg","type":"image\/jpeg"}],"author":"Cl\u00ednica Girona","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00ednica Girona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#article","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/"},"author":{"name":"Cl\u00ednica Girona","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601"},"headline":"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal","datePublished":"2023-08-28T09:43:00+00:00","dateModified":"2026-04-15T12:03:19+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/"},"wordCount":219,"publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"image":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/","url":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/","name":"Cl\u00ednica Girona pone en funcionamiento un nuevo servicio de Ecocardiograf\u00eda Fetal - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg","datePublished":"2023-08-28T09:43:00+00:00","dateModified":"2026-04-15T12:03:19+00:00","description":"Cl\u00ednica Girona pone en marcha un nuevo procedimiento de ecocardiograf\u00eda fetal, un m\u00e9todo preciso y seguro para la detecci\u00f3n de cardiopat\u00edas cong\u00e9nitas.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/Ecocardiografia-Fetal.jpg","width":1200,"height":900,"caption":"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/clinica-girona-posa-en-funcionament-un-nou-servei-decocardiografia-fetal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Cl\u00ednica Girona posa en funcionament un nou servei d\u2019Ecocardiografia Fetal"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]},{"@type":"Person","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601","name":"Cl\u00ednica Girona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","caption":"Cl\u00ednica Girona"},"sameAs":["https:\/\/clinicagirona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=32810"}],"version-history":[{"count":4,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32810\/revisions"}],"predecessor-version":[{"id":32861,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32810\/revisions\/32861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/32811"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=32810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/categories?post=32810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/tags?post=32810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}