{"id":32822,"date":"2023-02-02T11:59:00","date_gmt":"2023-02-02T10:59:00","guid":{"rendered":"https:\/\/clinicagirona.cat\/?p=32822"},"modified":"2026-04-15T14:03:19","modified_gmt":"2026-04-15T12:03:19","slug":"25-anos-de-resonancia-magnetica-en-girona","status":"publish","type":"post","link":"https:\/\/clinicagirona.cat\/es\/25-anys-de-ressonancia-magnetica-a-girona\/","title":{"rendered":"25 a\u00f1os de Resonancia Magn\u00e9tica en Girona"},"content":{"rendered":"<p><strong>Ciento cincuenta personas asistieron al acto de celebraci\u00f3n, el 16 de febrero<\/strong><\/p>\n\n\n\n<p>Este a\u00f1o se cumplen 25 a\u00f1os de la llegada de la resonancia magn\u00e9tica a Girona. El 2 de febrero de 1998 es una fecha importante para la sanidad de las comarcas gerundenses: se realiza la primera exploraci\u00f3n de resonancia magn\u00e9tica de las comarcas gerundenses en la Cl\u00ednica Girona. Este hecho ahorr\u00f3 el desplazamiento a Barcelona a cerca de 7.000 gerundenses para realizarse la prueba. La instauraci\u00f3n de la resonancia magn\u00e9tica supuso para la sanidad gerundense la disponibilidad de la t\u00e9cnica de imagen m\u00e1s avanzada para realizar diagn\u00f3sticos precisos de las enfermedades a nivel de todo el cuerpo.<\/p>\n\n\n\n<p>El acto de celebraci\u00f3n de este aniversario tuvo lugar el jueves 16 de febrero de 2023, a las 7 de la tarde, en el Sal\u00f3n de Actos de Cl\u00ednica Girona, con unas palabras de presentaci\u00f3n a cargo del Gerente de Cl\u00ednica Girona Sr. Carles Esp\u00edgol, y del Dr. Miquel Carreras, Sr. Carles Esp\u00edgol, Gerente de la Regi\u00f3n Sanitaria Girona del Servei Catal\u00e0 de la Salut, que dieron paso a tres exposiciones cortas:<\/p>\n\n\n\n<p>\u201c25 a\u00f1os de Resonancia Magn\u00e9tica en Girona \u2013 Cl\u00ednica Girona, a cargo del Dr. Kai Vilanova, Codirector Servicio de Resonancia Magn\u00e9tica - Cl\u00ednica Girona<\/p>\n\n\n\n<p>\u201cIndicaciones actuales de la Resonancia Magn\u00e9tica\u201d, a cargo del Dr. Joaquim Barcel\u00f3, Codirector Servicio de Resonancia Magn\u00e9tica \u2013 Cl\u00ednica Girona<\/p>\n\n\n\n<p>\u201c25 a\u00f1os m\u00e1s de avances en Resonancia Magn\u00e9tica\u201d, a cargo del Dr. Roberto Garc\u00eda Figueiras, Jefe de Servicio Departamento de Radiolog\u00eda Hospital Cl\u00ednico Universitario.<\/p>\n\n\n\n<p>El acto cont\u00f3 con la asistencia de medio centenar de personas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1065\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-1065x800.jpg\" alt=\"25 a\u00f1os de Resonancia Magn\u00e9tica en Girona\" class=\"wp-image-32826\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-1065x800.jpg 1065w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-400x300.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-768x577.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-430x323.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-700x526.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP-150x113.jpg 150w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg 1200w\" sizes=\"(max-width: 1065px) 100vw, 1065px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO.jpg\" alt=\"\" class=\"wp-image-32827\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO-400x267.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO-768x512.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO-430x287.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO-700x467.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_KAI-25-RESSO-150x100.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p><strong>460.000 exploraciones en 25 a\u00f1os<\/strong><\/p>\n\n\n\n<p>El Servicio de Resonancia Magn\u00e9tica de la Cl\u00ednica Girona se inici\u00f3 con un aparato que ofrec\u00eda las prestaciones necesarias para la tecnolog\u00eda del momento. El aumento de la demanda de la t\u00e9cnica hizo que la Cl\u00ednica Girona instalara un segundo aparato a finales del a\u00f1o 1999. En este caso se trataba de un aparato que era especialmente \u00fatil para las personas que ten\u00edan claustrofobia. La progresiva demanda de la t\u00e9cnica y tambi\u00e9n la gran evoluci\u00f3n de la tecnolog\u00eda de la resonancia magn\u00e9tica hizo que se instalaran dos aparatos m\u00e1s durante estos a\u00f1os. Uno de estos aparatos, instalado en el a\u00f1o 2009, permite estudiar el cuerpo en bipedestaci\u00f3n (de pie) lo que mejora la capacidad de diagnosticar enfermedades de la columna que en los estudios habituales no pueden detectar. Durante estos 25 a\u00f1os se han realizado en el Servicio 460.000 exploraciones de resonancia magn\u00e9tica.<\/p>\n\n\n\n<p><strong>La gran evoluci\u00f3n tecnol\u00f3gica<\/strong><\/p>\n\n\n\n<p>La gran evoluci\u00f3n tecnol\u00f3gica de la radiolog\u00eda y especialmente debido al progreso espectacular de la resonancia magn\u00e9tica durante estos 25 a\u00f1os ha tenido un reflejo en el propio Servicio, por la actualizaci\u00f3n de los aparatos y especialmente en ofrecer todas las prestaciones m\u00e1s innovadoras que la t\u00e9cnica permite realizar en un estudio de resonancia magn\u00e9tica. Actualmente en la nueva Cl\u00ednica Girona se dispone de todos los diferentes tipos de RM disponibles desde la m\u00e1xima potencia en 3T, en 1.5T y tambi\u00e9n equipamiento abierto para pacientes claustrof\u00f3bicos con la posibilidad de realizar estudios en bipedestaci\u00f3n. Hoy en d\u00eda es posible estudiar y diagnosticar cualquier enfermedad de nuestro cuerpo gracias a la extraordinaria capacidad de la resonancia magn\u00e9tica para mostrar im\u00e1genes anat\u00f3micas de la m\u00e1xima calidad. Es posible realizar estudios de cualquier \u00e1rea anat\u00f3mica e incluso se pueden obtener im\u00e1genes en tiempo real, en movimiento, como es el coraz\u00f3n; con la m\u00e1xima precisi\u00f3n.<\/p>\n\n\n\n<p>El Servicio de Resonancia Magn\u00e9tica de la Cl\u00ednica Girona est\u00e1 dirigido desde su inicio por los Dres. Joan Carles Vilanova y Joaquim Barcel\u00f3, especialistas en radiodiagn\u00f3stico. Ambos m\u00e9dicos radi\u00f3logos incorporaron las exploraciones m\u00e1s avanzadas desde el principio; y dada la propia evoluci\u00f3n de la resonancia magn\u00e9tica, durante estos a\u00f1os se han ido incorporando todas las t\u00e9cnicas m\u00e1s innovadoras que la t\u00e9cnica permite realizar hoy en d\u00eda. La dedicaci\u00f3n de los Dres. Vilanova y Barcel\u00f3 al desarrollo y evoluci\u00f3n de la propia t\u00e9cnica de resonancia magn\u00e9tica ha hecho que el Servicio sea hoy en d\u00eda un referente en el \u00e1mbito espa\u00f1ol y a nivel internacional en resonancia magn\u00e9tica, especialmente en el campo oncol\u00f3gico y sobre todo en el c\u00e1ncer de pr\u00f3stata.<\/p>\n\n\n\n<p><strong>Pioneros<\/strong><\/p>\n\n\n\n<p>Precisamente el Servicio ha sido pionero en el estado espa\u00f1ol en implantar una t\u00e9cnica muy \u00fatil en el c\u00e1ncer como es la resonancia magn\u00e9tica de todo el cuerpo. Desde hace 3 a\u00f1os, el Servicio ha sido pionero en el Estado espa\u00f1ol en realizar biopsias de pr\u00f3stata con un aparato rob\u00f3tico en el mismo equipo de resonancia magn\u00e9tica. Durante estos a\u00f1os los dos radi\u00f3logos han participado en m\u00faltiples trabajos de investigaci\u00f3n en diferentes campos de la medicina, habiendo publicado m\u00e1s de 120 art\u00edculos en las revistas de mayor impacto y habiendo presentado estos estudios en los diferentes congresos nacionales e internacionales. Muchos de estos trabajos han sido reconocidos con diferentes premios en los congresos de radiolog\u00eda; destacando la m\u00e1xima distinci\u00f3n en el Congreso Europeo de Radiolog\u00eda en el a\u00f1o 2006 y en el a\u00f1o 2010 en el congreso mundial de radiolog\u00eda que se celebra anualmente en Chicago, EEUU.<\/p>\n\n\n\n<p>Fruto de estos trabajos de investigaci\u00f3n, el Servicio de Resonancia Magn\u00e9tica de la Cl\u00ednica Girona fue reconocido al recibir el premio Bonastruc \u00e7a Porta 2016 del COMG \u201cpor su trayectoria profesional y por la innovaci\u00f3n en el campo oncol\u00f3gico\u201d. En 2018 se public\u00f3 un libro de referencia internacional de la resonancia magn\u00e9tica en el c\u00e1ncer de pr\u00f3stata, editado con la participaci\u00f3n de los directores del Servicio, los Dres. Vilanova y Barcel\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I.jpg\" alt=\"\" class=\"wp-image-32823\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I-400x225.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I-768x432.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I-430x242.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I-700x394.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_ROBERTO-25-RESSO-I-150x84.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO.jpg\" alt=\"\" class=\"wp-image-32825\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-400x300.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-1067x800.jpg 1067w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-768x576.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-430x323.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-700x525.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_PONENTS-JUNTS-TOTS-25-RESSO-150x113.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO.jpg\" alt=\"\" class=\"wp-image-32828\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-400x300.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-1067x800.jpg 1067w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-768x576.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-430x323.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-700x525.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_GERENTS-EXPO-25-RESSO-150x113.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO.jpg\" alt=\"\" class=\"wp-image-32824\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO-400x267.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO-768x512.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO-430x287.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO-700x467.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_BARCELO-25-RESSO-150x100.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>El 2 de febrero de 1998 es una fecha importante para la sanidad de las comarcas gerundenses: se realiza la primera exploraci\u00f3n de resonancia magn\u00e9tica de las comarcas gerundenses en la Cl\u00ednica Girona.<\/p>","protected":false},"author":1,"featured_media":32826,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[],"class_list":["post-32822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activitats"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"El 2 de febrer de 1998 \u00e9s una data important per la sanitat de les comarques gironines: Es realitza la primera exploraci\u00f3 de resson\u00e0ncia magn\u00e8tica de les comarques gironines a la Cl\u00ednica Girona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/25-anos-de-resonancia-magnetica-en-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"El 2 de febrer de 1998 \u00e9s una data important per la sanitat de les comarques gironines: Es realitza la primera exploraci\u00f3 de resson\u00e0ncia magn\u00e8tica de les comarques gironines a la Cl\u00ednica Girona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/25-anos-de-resonancia-magnetica-en-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T10:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00ednica Girona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00ednica Girona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/\"},\"author\":{\"name\":\"Cl\u00ednica Girona\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\"},\"headline\":\"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona\",\"datePublished\":\"2023-02-02T10:59:00+00:00\",\"dateModified\":\"2026-04-15T12:03:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/\"},\"wordCount\":1027,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg\",\"articleSection\":[\"Activitats\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/\",\"name\":\"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg\",\"datePublished\":\"2023-02-02T10:59:00+00:00\",\"dateModified\":\"2026-04-15T12:03:19+00:00\",\"description\":\"El 2 de febrer de 1998 \u00e9s una data important per la sanitat de les comarques gironines: Es realitza la primera exploraci\u00f3 de resson\u00e0ncia magn\u00e8tica de les comarques gironines a la Cl\u00ednica Girona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg\",\"width\":1200,\"height\":901,\"caption\":\"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/25-anys-de-ressonancia-magnetica-a-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\",\"name\":\"Cl\u00ednica Girona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"caption\":\"Cl\u00ednica Girona\"},\"sameAs\":[\"https:\\\/\\\/clinicagirona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25 a\u00f1os de Resonancia Magn\u00e9tica en Girona - Cl\u00ednica Girona","description":"El 2 de febrero de 1998 es una fecha importante para la sanidad de las comarcas gerundenses: se realiza la primera exploraci\u00f3n de resonancia magn\u00e9tica de las comarcas gerundenses en la Cl\u00ednica Girona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/25-anos-de-resonancia-magnetica-en-girona\/","og_locale":"es_ES","og_type":"article","og_title":"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona - Cl\u00ednica Girona","og_description":"El 2 de febrer de 1998 \u00e9s una data important per la sanitat de les comarques gironines: Es realitza la primera exploraci\u00f3 de resson\u00e0ncia magn\u00e8tica de les comarques gironines a la Cl\u00ednica Girona.","og_url":"https:\/\/clinicagirona.cat\/es\/25-anos-de-resonancia-magnetica-en-girona\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_published_time":"2023-02-02T10:59:00+00:00","article_modified_time":"2026-04-15T12:03:19+00:00","og_image":[{"width":1200,"height":901,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg","type":"image\/jpeg"}],"author":"Cl\u00ednica Girona","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00ednica Girona","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#article","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/"},"author":{"name":"Cl\u00ednica Girona","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601"},"headline":"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona","datePublished":"2023-02-02T10:59:00+00:00","dateModified":"2026-04-15T12:03:19+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/"},"wordCount":1027,"publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"image":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg","articleSection":["Activitats"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/","url":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/","name":"25 a\u00f1os de Resonancia Magn\u00e9tica en Girona - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg","datePublished":"2023-02-02T10:59:00+00:00","dateModified":"2026-04-15T12:03:19+00:00","description":"El 2 de febrero de 1998 es una fecha importante para la sanidad de las comarcas gerundenses: se realiza la primera exploraci\u00f3n de resonancia magn\u00e9tica de las comarcas gerundenses en la Cl\u00ednica Girona.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/05\/A_W_LA-FOTO-RESSO-25-EQUIP.jpg","width":1200,"height":901,"caption":"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/25-anys-de-ressonancia-magnetica-a-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"25 anys de Resson\u00e0ncia Magn\u00e8tica a Girona"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]},{"@type":"Person","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601","name":"Cl\u00ednica Girona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","caption":"Cl\u00ednica Girona"},"sameAs":["https:\/\/clinicagirona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=32822"}],"version-history":[{"count":2,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32822\/revisions"}],"predecessor-version":[{"id":32864,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/32822\/revisions\/32864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/32826"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=32822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/categories?post=32822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/tags?post=32822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}