{"id":33008,"date":"2021-03-17T11:32:00","date_gmt":"2021-03-17T10:32:00","guid":{"rendered":"https:\/\/clinicagirona.cat\/?p=33008"},"modified":"2026-04-15T14:07:54","modified_gmt":"2026-04-15T12:07:54","slug":"el-dr-santiago-aparicio-alergologo-de-clinica-girona-publica-un-libro-sobre-medicina-aplicada-en-la-navegacion","status":"publish","type":"post","link":"https:\/\/clinicagirona.cat\/es\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/","title":{"rendered":"El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, publica un libro sobre medicina aplicada a la navegaci\u00f3n"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>El libro, publicado por la editorial McGraw Hill, es fruto de sus dos pasiones: la medicina y el mar.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, ha escrito un libro sobre \u201cMedicina aplicada a la navegaci\u00f3n\u201d, que ha sido publicado por la editorial educativa norteamericana McGraw Hill.\u201c<em>Como m\u00e9dico y navegante<\/em>\u201c, afirma el Dr. Santiago Aparicio, gran aficionado a la navegaci\u00f3n, patr\u00f3n de embarcaciones y buceador deportivo de primera clase, \u201cf<em>al tiempo que pensaba en la necesidad de que hubiera un libro de consulta m\u00e9dica que apoyara a los navegantes en general y en concreto tambi\u00e9n a los deportivos, ante situaciones de emergencias y tambi\u00e9n en cuestiones m\u00e9dicas habituales a bordo de un barco<\/em>\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el Dr. Aparicio: \u201cDesafortunadamente, en el mar nos encontramos ante situaciones que en tierra tienen un enfoque bien diferente y es dif\u00edcil saber qu\u00e9 hacer cuando se produce un accidente, de repente, y hay que actuar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El libro \u201cMedicina aplicada a la navegaci\u00f3n\u201d, muy intuitivo, est\u00e1 ordenado por cap\u00edtulos seg\u00fan el tipo de navegaci\u00f3n y seg\u00fan las personas que haya a bordo. En los distintos apartados el Dr. Aparicio incluye la medicaci\u00f3n recomendada para cada enfermedad y accidente, en funci\u00f3n de los medicamentos de las distintas farmaciolas, y tambi\u00e9n hace un listado de medicamentos recomendados aparte de los que ya incluyen las farmaciolas habituales. En el ap\u00e9ndice final hay una gu\u00eda completa de la dosificaci\u00f3n de esta medicaci\u00f3n recomendada tanto para adultos como para ni\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"744\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\" alt=\"El Dr. Santiago Aparicio publica un llibre sobre medicina aplicada a la navegaci\u00f3\" class=\"wp-image-33009\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio-400x248.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio-768x476.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio-430x267.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio-700x434.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio-150x93.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">El Dr. Santiago Aparicio publica un llibre sobre medicina aplicada a la navegaci\u00f3<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un libro de lectura, pero sobretodo de consulta\u201d, concluye el Dr. Aparicio, y espero que se convierta en una herramienta \u00fatil de apoyo para las emergencias m\u00e9dicas n\u00e1uticas\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, ha escrito un libro sobre \u201cMedicina aplicada a la navegaci\u00f3n\u201d, que ha sido publicado por la editorial educativa estadounidense McGraw Hill.<\/p>","protected":false},"author":1,"featured_media":33009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-33008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3 - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"El Dr. Santiago Aparicio, \u00a0al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, ha fet un llibre sobre \u201cMedicina aplicada a la navegaci\u00f3\u201d, que ha estat publicat per l\u2019editorial educativa nord-americana McGraw Hill.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/el-dr-santiago-aparicio-alergologo-de-clinica-girona-publica-un-libro-sobre-medicina-aplicada-en-la-navegacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3 - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"El Dr. Santiago Aparicio, \u00a0al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, ha fet un llibre sobre \u201cMedicina aplicada a la navegaci\u00f3\u201d, que ha estat publicat per l\u2019editorial educativa nord-americana McGraw Hill.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/el-dr-santiago-aparicio-alergologo-de-clinica-girona-publica-un-libro-sobre-medicina-aplicada-en-la-navegacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T10:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:07:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00ednica Girona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00ednica Girona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/\"},\"author\":{\"name\":\"Cl\u00ednica Girona\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\"},\"headline\":\"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3\",\"datePublished\":\"2021-03-17T10:32:00+00:00\",\"dateModified\":\"2026-04-15T12:07:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/\",\"name\":\"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3 - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\",\"datePublished\":\"2021-03-17T10:32:00+00:00\",\"dateModified\":\"2026-04-15T12:07:54+00:00\",\"description\":\"El Dr. Santiago Aparicio, \u00a0al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, ha fet un llibre sobre \u201cMedicina aplicada a la navegaci\u00f3\u201d, que ha estat publicat per l\u2019editorial educativa nord-americana McGraw Hill.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg\",\"width\":1200,\"height\":744,\"caption\":\"El Dr. Santiago Aparicio publica un llibre sobre medicina aplicada a la navegaci\u00f3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\",\"name\":\"Cl\u00ednica Girona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"caption\":\"Cl\u00ednica Girona\"},\"sameAs\":[\"https:\\\/\\\/clinicagirona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, publica un libro sobre medicina aplicada a la navegaci\u00f3n - Cl\u00ednica Girona","description":"El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, ha escrito un libro sobre \u201cMedicina aplicada a la navegaci\u00f3n\u201d, que ha sido publicado por la editorial educativa estadounidense McGraw Hill.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/el-dr-santiago-aparicio-alergologo-de-clinica-girona-publica-un-libro-sobre-medicina-aplicada-en-la-navegacion\/","og_locale":"es_ES","og_type":"article","og_title":"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3 - Cl\u00ednica Girona","og_description":"El Dr. Santiago Aparicio, \u00a0al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, ha fet un llibre sobre \u201cMedicina aplicada a la navegaci\u00f3\u201d, que ha estat publicat per l\u2019editorial educativa nord-americana McGraw Hill.","og_url":"https:\/\/clinicagirona.cat\/es\/el-dr-santiago-aparicio-alergologo-de-clinica-girona-publica-un-libro-sobre-medicina-aplicada-en-la-navegacion\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_published_time":"2021-03-17T10:32:00+00:00","article_modified_time":"2026-04-15T12:07:54+00:00","og_image":[{"width":1200,"height":744,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg","type":"image\/jpeg"}],"author":"Cl\u00ednica Girona","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00ednica Girona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#article","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/"},"author":{"name":"Cl\u00ednica Girona","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601"},"headline":"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3","datePublished":"2021-03-17T10:32:00+00:00","dateModified":"2026-04-15T12:07:54+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/"},"wordCount":324,"publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"image":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/","url":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/","name":"El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, publica un libro sobre medicina aplicada a la navegaci\u00f3n - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg","datePublished":"2021-03-17T10:32:00+00:00","dateModified":"2026-04-15T12:07:54+00:00","description":"El Dr. Santiago Aparicio, alerg\u00f3logo de Cl\u00ednica Girona, ha escrito un libro sobre \u201cMedicina aplicada a la navegaci\u00f3n\u201d, que ha sido publicado por la editorial educativa estadounidense McGraw Hill.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Llibre-sobre-medicina-aplicada-a-la-navegacio.jpg","width":1200,"height":744,"caption":"El Dr. Santiago Aparicio publica un llibre sobre medicina aplicada a la navegaci\u00f3"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/el-dr-santiago-aparicio-allergoleg-de-clinica-girona-publica-un-llibre-sobre-medicina-aplicada-a-la-navegacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"El Dr. Santiago Aparicio, al\u00b7lerg\u00f2leg de Cl\u00ednica Girona, publica un llibre sobre medicina aplicada a la navegaci\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]},{"@type":"Person","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601","name":"Cl\u00ednica Girona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","caption":"Cl\u00ednica Girona"},"sameAs":["https:\/\/clinicagirona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=33008"}],"version-history":[{"count":1,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33008\/revisions"}],"predecessor-version":[{"id":33010,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33008\/revisions\/33010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/33009"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=33008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/categories?post=33008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/tags?post=33008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}