{"id":33026,"date":"2020-07-28T13:09:00","date_gmt":"2020-07-28T11:09:00","guid":{"rendered":"https:\/\/clinicagirona.cat\/?p=33026"},"modified":"2026-04-15T14:07:54","modified_gmt":"2026-04-15T12:07:54","slug":"clinica-girona-comprometidos-con-ustedes-y-con-su-salud","status":"publish","type":"post","link":"https:\/\/clinicagirona.cat\/es\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/","title":{"rendered":"Cl\u00ednica Girona: Comprometidos con ustedes y con su Salud"},"content":{"rendered":"<p>Ante la pandemia #Covid19, los profesionales sanitarios de Cl\u00ednica Girona continuamos trabajando incansablemente para hacer frente a los problemas de Salud de nuestros pacientes. Comprometidos con vosotros y con vuestra Salud.<\/p>\n\n\n\n<p>Actualmente tenemos pacientes ingresados con #Covid19. Para poder hacer frente al reto sanitario planteado por la pandemia del coronavirus hemos habilitado dos plantas de hospitalizaci\u00f3n, la sexta y la s\u00e9ptima, para acoger pacientes con #Covid19 (con capacidad para 36 pacientes) y hemos ampliado las camas de UCI de 6 a 10, sumando las acondicionadas en el \u00e1rea quir\u00fargica y en el Servicio de Nefrolog\u00eda y Hemodi\u00e1lisis de Cl\u00ednica Girona.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"676\" src=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\" alt=\"Cl\u00ednica Girona: Comprometidos con ustedes y con su Salud\" class=\"wp-image-33027\" srcset=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg 1200w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut-400x225.jpg 400w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut-768x433.jpg 768w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut-430x242.jpg 430w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut-700x394.jpg 700w, https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut-150x85.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p><strong>Donaciones de material<\/strong><\/p>\n\n\n\n<p>Durante los primeros d\u00edas, de escasez de recursos, pudimos hacer frente al virus gracias a las aportaciones solidarias de personas, empresas y entidades que nos hicieron donaciones de material de protecci\u00f3n individual para los profesionales sanitarios. Hemos recibido tambi\u00e9n donaciones de otros tipos, como de cafeteras, caf\u00e9, y reposter\u00eda, que hacen m\u00e1s llevaderas las agotadoras jornadas de lucha contra la pandemia. <\/p>\n\n\n\n<p><strong>Dibujos y escritos de apoyo<\/strong><\/p>\n\n\n\n<p>Tambi\u00e9n hemos recibido un mont\u00f3n de cartas, escritas desde el coraz\u00f3n, y dibujos de chicas y chicos, que nos dan apoyo y fuerza en estos momentos duros que estamos viviendo. Los escritos y los dibujos dirigidos a los pacientes con Covid19 los repartimos con las bandejas del almuerzo por las habitaciones de las plantas, y son una alegr\u00eda cada d\u00eda para las personas ingresadas. Los dirigidos al personal asistencial, los colgamos en los controles de enfermer\u00eda, en los vestuarios o por las paredes de la Cl\u00ednica, para que los puedan ver todos y todos puedan disfrutar. Muchas gracias, nos dan \u00e1nimos.<\/p>\n\n\n\n<p><strong>Gracias por su apoyo. \u00a1Saldremos de esta!<\/strong><\/p>\n\n\n\n<p>Recibimos cada d\u00eda tambi\u00e9n, puntualmente a las 8 de la tarde, el aplauso de la poblaci\u00f3n que sale a los balcones y ventanas y nos hacen llegar su calor.<\/p>\n\n\n\n<iframe width=\"1200\" height=\"575\" src=\"https:\/\/www.youtube.com\/embed\/f67KdMAFAvw?si=ZSx9ShNQkl1agzhj\" title=\"Reproductor de YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<iframe width=\"1200\" height=\"575\" src=\"https:\/\/www.youtube.com\/embed\/SM6nqcYdvn0?si=2ZHu17AgFwoRPrpp\" title=\"Reproductor de YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<iframe width=\"1200\" height=\"575\" src=\"https:\/\/www.youtube.com\/embed\/drMhGGYN9XA?si=YcX5MuBUaGAm2yOl\" title=\"Reproductor de YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Para poder hacer frente al reto sanitario planteado por la pandemia de coronavirus hemos habilitado dos plantas de hospitalizaci\u00f3n, la sexta y la s\u00e9ptima, para acoger pacientes con Covid19.<\/p>","protected":false},"author":1,"featured_media":33027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-33026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut - Cl\u00ednica Girona<\/title>\n<meta name=\"description\" content=\"Per poder fer front al repte sanitari plantejat per la pand\u00e8mia del coronavirus hem habilitat dues plantes d\u2019hospitalitzaci\u00f3, la sisena i la setena, per acollir pacients amb Covid19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicagirona.cat\/es\/clinica-girona-comprometidos-con-ustedes-y-con-su-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut - Cl\u00ednica Girona\" \/>\n<meta property=\"og:description\" content=\"Per poder fer front al repte sanitari plantejat per la pand\u00e8mia del coronavirus hem habilitat dues plantes d\u2019hospitalitzaci\u00f3, la sisena i la setena, per acollir pacients amb Covid19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicagirona.cat\/es\/clinica-girona-comprometidos-con-ustedes-y-con-su-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Girona\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/clinicagirona\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-28T11:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:07:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00ednica Girona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00ednica Girona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/\"},\"author\":{\"name\":\"Cl\u00ednica Girona\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\"},\"headline\":\"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut\",\"datePublished\":\"2020-07-28T11:09:00+00:00\",\"dateModified\":\"2026-04-15T12:07:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/\",\"name\":\"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut - Cl\u00ednica Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\",\"datePublished\":\"2020-07-28T11:09:00+00:00\",\"dateModified\":\"2026-04-15T12:07:54+00:00\",\"description\":\"Per poder fer front al repte sanitari plantejat per la pand\u00e8mia del coronavirus hem habilitat dues plantes d\u2019hospitalitzaci\u00f3, la sisena i la setena, per acollir pacients amb Covid19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg\",\"width\":1200,\"height\":676,\"caption\":\"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/clinicagirona.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#website\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"name\":\"Cl\u00ednica Girona\",\"description\":\"Cuidem la teva salut, et cuidem a tu\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicagirona.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#organization\",\"name\":\"Cl\u00ednica Girona\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicagirona.cat\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/clinica-girona-logo-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cl\u00ednica Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/clinicagirona\",\"https:\\\/\\\/www.instagram.com\\\/clinicagirona\\\/\",\"http:\\\/\\\/www.youtube.com\\\/clinicagirona\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/clnica-girona-130222b6\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicagirona.cat\\\/#\\\/schema\\\/person\\\/ec728b8119aaf903be216cb0ae2ae601\",\"name\":\"Cl\u00ednica Girona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g\",\"caption\":\"Cl\u00ednica Girona\"},\"sameAs\":[\"https:\\\/\\\/clinicagirona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cl\u00ednica Girona: Comprometidos con ustedes y con su Salud - Cl\u00ednica Girona","description":"Para poder hacer frente al reto sanitario planteado por la pandemia de coronavirus hemos habilitado dos plantas de hospitalizaci\u00f3n, la sexta y la s\u00e9ptima, para acoger pacientes con Covid19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicagirona.cat\/es\/clinica-girona-comprometidos-con-ustedes-y-con-su-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut - Cl\u00ednica Girona","og_description":"Per poder fer front al repte sanitari plantejat per la pand\u00e8mia del coronavirus hem habilitat dues plantes d\u2019hospitalitzaci\u00f3, la sisena i la setena, per acollir pacients amb Covid19.","og_url":"https:\/\/clinicagirona.cat\/es\/clinica-girona-comprometidos-con-ustedes-y-con-su-salud\/","og_site_name":"Cl\u00ednica Girona","article_publisher":"http:\/\/www.facebook.com\/clinicagirona","article_published_time":"2020-07-28T11:09:00+00:00","article_modified_time":"2026-04-15T12:07:54+00:00","og_image":[{"width":1200,"height":676,"url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg","type":"image\/jpeg"}],"author":"Cl\u00ednica Girona","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00ednica Girona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#article","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/"},"author":{"name":"Cl\u00ednica Girona","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601"},"headline":"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut","datePublished":"2020-07-28T11:09:00+00:00","dateModified":"2026-04-15T12:07:54+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/"},"wordCount":328,"publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"image":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/","url":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/","name":"Cl\u00ednica Girona: Comprometidos con ustedes y con su Salud - Cl\u00ednica Girona","isPartOf":{"@id":"https:\/\/clinicagirona.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#primaryimage"},"image":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg","datePublished":"2020-07-28T11:09:00+00:00","dateModified":"2026-04-15T12:07:54+00:00","description":"Para poder hacer frente al reto sanitario planteado por la pandemia de coronavirus hemos habilitado dos plantas de hospitalizaci\u00f3n, la sexta y la s\u00e9ptima, para acoger pacientes con Covid19.","breadcrumb":{"@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#primaryimage","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2025\/06\/Clinica-Girona-Compromesos-amb-vosaltres-i-amb-la-vostra-Salut.jpg","width":1200,"height":676,"caption":"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicagirona.cat\/clinica-girona-compromesos-amb-vosaltres-i-amb-la-vostra-salut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/clinicagirona.cat\/"},{"@type":"ListItem","position":2,"name":"Cl\u00ednica Girona: Compromesos amb vosaltres i amb la vostra Salut"}]},{"@type":"WebSite","@id":"https:\/\/clinicagirona.cat\/#website","url":"https:\/\/clinicagirona.cat\/","name":"Cl\u00ednica Girona","description":"Cuidamos tu salud, te cuidamos a ti","publisher":{"@id":"https:\/\/clinicagirona.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicagirona.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicagirona.cat\/#organization","name":"Cl\u00ednica Girona","url":"https:\/\/clinicagirona.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/","url":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","contentUrl":"https:\/\/clinicagirona.cat\/wp-content\/uploads\/2026\/04\/clinica-girona-logo-quadrat.jpg","width":1000,"height":1000,"caption":"Cl\u00ednica Girona"},"image":{"@id":"https:\/\/clinicagirona.cat\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/clinicagirona","https:\/\/www.instagram.com\/clinicagirona\/","http:\/\/www.youtube.com\/clinicagirona","http:\/\/www.linkedin.com\/in\/clnica-girona-130222b6\/"]},{"@type":"Person","@id":"https:\/\/clinicagirona.cat\/#\/schema\/person\/ec728b8119aaf903be216cb0ae2ae601","name":"Cl\u00ednica Girona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec10c50b8f12b9e82862c14ace47e70739a9e377b28c1a487f71b26e36e20e2?s=96&d=mm&r=g","caption":"Cl\u00ednica Girona"},"sameAs":["https:\/\/clinicagirona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/comments?post=33026"}],"version-history":[{"count":2,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33026\/revisions"}],"predecessor-version":[{"id":33029,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/posts\/33026\/revisions\/33029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media\/33027"}],"wp:attachment":[{"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/media?parent=33026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/categories?post=33026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicagirona.cat\/es\/wp-json\/wp\/v2\/tags?post=33026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}